{"id":3013,"date":[],"date_gmt":"2019-12-09T15:37:48","guid":{"rendered":"https:\/\/dev.lasemaineduson.be\/event\/sieste-musicale\/"},"modified":"2023-11-14T14:27:21","modified_gmt":"2023-11-14T13:27:21","slug":"sieste-musicale","status":"publish","type":"event","link":"https:\/\/www.lasemaineduson.be\/en\/event\/sieste-musicale\/","title":{"rendered":"Sieste Musicale"},"content":{"rendered":"<p><strong>Confortablement install\u00e9 sur des coussins, venez profiter d\u2019une ambiance musicale d\u00e9tendue propos\u00e9e par Nathalie Loriers et Jacques Pili.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Leur exp\u00e9rience assez in\u00e9dite dans le domaine des musiques dites \u2018\u2019m\u00e9ditatives\u2018\u2019 m\u00e8nera les deux musiciens aguerris que sont Nathalie Lauriers et Jacques Pili \u00e0 proposer une improvisation de piano et bols chantants acoustique, pendant laquelle les auditeurs allong\u00e9s ou assis pourront tant\u00f4t s&#8217;endormir, tant\u00f4t trouver un \u00e9tat de profonde relaxation et, dans tous les cas, embarquer pour un voyage musical d\u2019imagerie.<\/p>\n<p>Nathalie Loriers continue de tracer de nouvelles voies musicales. Bien connue des amateurs de jazz, l\u2019artiste poursuit depuis plusieurs ann\u00e9es une formation sur l\u2019\u00e9tude de l\u2019utilisation du son dans un but th\u00e9rapeutique apr\u00e8s de l\u2019anthropologue am\u00e9ricaine Pat Moffit Cook. Elle \u00e9tudie plus sp\u00e9cialement les vertus de certains param\u00e8tres sonores sur la relaxation et le sommeil, qu\u2019elle exp\u00e9rimente d\u2019abord sur elle-m\u00eame, pour ensuite traduire le r\u00e9sultat de ses observations lors d\u2019improvisations pianistiques. Fascin\u00e9e et interpell\u00e9es par la d\u00e9couverte du pouvoir du son des bols chantants, cr\u00e9\u00e9s et jou\u00e9s par Jacques Pili.<\/p>\n<p>Jacques Pili est un musicien d\u2019ouverture, tanto\u0302t bassiste dans le milieu pop (Maurane, Michel Fugain, The Voice\u2026.),\u00a0tanto\u0302t contrebassiste dans le milieu jazz (Chrystel Wautier, Marco Locurcio, Lorenzo Di Maio&#8230;), il\u00a0suit \u00e9galement les enseignements de Pat Moffit Cook depuis plusieurs ann\u00e9es. Par ailleurs, sa rencontre avec Ton Akkermans aupr\u00e8s de qui il \u00e9tudie les secrets de la fabrication des bols vient compl\u00e9ter les enseignements de Pat Moffit Cook.\u00a0Il jouera sur des instruments principalement fabrique\u0301s de ses mains :\u00a0bols, cloches, gongs et autres.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"lieu":[993],"region":[],"event_type":[],"edition":[476],"class_list":["post-3013","event","type-event","status-publish","hentry","lieu-le-delta","edition-476"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3013\/revisions"}],"predecessor-version":[{"id":3438,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3013\/revisions\/3438"}],"wp:attachment":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/media?parent=3013"}],"wp:term":[{"taxonomy":"date","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/date?post=3013"},{"taxonomy":"lieu","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/lieu?post=3013"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/region?post=3013"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event_type?post=3013"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/edition?post=3013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}