{"id":3608,"date":[],"date_gmt":"2021-08-16T06:44:39","guid":{"rendered":"https:\/\/dev.lasemaineduson.be\/event\/curupira-installation-felix-blume\/"},"modified":"2023-11-14T14:27:05","modified_gmt":"2023-11-14T13:27:05","slug":"curupira-installation-felix-blume","status":"publish","type":"event","link":"https:\/\/www.lasemaineduson.be\/en\/event\/curupira-installation-felix-blume\/","title":{"rendered":"CURUPIRA &#8211; INSTALLATION &#8211; F\u00c9LIX BLUME"},"content":{"rendered":"<p><strong>CURUPIRA, B\u00caTE DES BOIS\u00a0 &#8211; <\/strong><strong>F\u00e9lix Blume <\/strong><\/p>\n<p><strong>Vernissage de l\u2019installation sonore le mardi \u00e0 18h (Studio 2 Flagey)<\/strong><\/p>\n<p>Au c\u0153ur de l\u2019Amazonie, les habitants de Tauary nous invitent \u00e0 \u00e9couter les sons de leur for\u00eat, avec ses oiseaux et ses animaux. Certains sons \u00e9tranges apparaissent pourtant. Une cr\u00e9ature r\u00f4de entre les arbres. Ceux qui l&#8217;ont d\u00e9j\u00e0 entendue, ou tr\u00e8s peu vue, et ceux qui l\u2019ont rencontr\u00e9e n\u2019en sont jamais revenus. Elle charme, elle enchante, elle rend fou, elle emm\u00e8ne les gens, elle les pousse \u00e0 se perdre. Chacun la raconte \u00e0 sa mani\u00e8re et tente de d\u00e9crypter ses appels.\u00a0<em>Curupira, b\u00eate des bois<\/em>\u00a0nous emm\u00e8ne \u00e0 la recherche de cet \u00eatre. Une r\u00e9flexion sur les mythes et sur leur place dans le monde contemporain, un thriller sonore en pleine jungle.<\/p>\n<p><a href=\"https:\/\/felixblume.com\/curupira\/\" target=\"_blank\" rel=\"noopener\">https:\/\/felixblume.com\/curupira\/<\/a><\/p>\n<p><strong>Du 31\/08 au 02\/09 \u00e0 Flagey (17:00 &gt; 21:00)<\/strong><\/p>\n<p><strong>Et jusqu&#8217;au 05\/09 (14:00 &gt; 18:00) \u00e0 AUTONOMIE (Second vernissage le mercredi 01\/09 \u00e0 18:00)<\/strong><\/p>\n","protected":false},"author":1,"featured_media":1640,"template":"","meta":{"_acf_changed":false,"footnotes":""},"lieu":[1017],"region":[],"event_type":[],"edition":[7],"class_list":["post-3608","event","type-event","status-publish","has-post-thumbnail","hentry","lieu-autonomie","edition-7"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3608\/revisions"}],"predecessor-version":[{"id":5394,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3608\/revisions\/5394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/media\/1640"}],"wp:attachment":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/media?parent=3608"}],"wp:term":[{"taxonomy":"date","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/date?post=3608"},{"taxonomy":"lieu","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/lieu?post=3608"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/region?post=3608"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event_type?post=3608"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/edition?post=3608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}