{"id":3707,"date":[],"date_gmt":"2022-12-18T08:40:41","guid":{"rendered":"https:\/\/dev.lasemaineduson.be\/event\/atelier-matrices-alicia-jeannin\/"},"modified":"2023-11-14T14:26:57","modified_gmt":"2023-11-14T13:26:57","slug":"atelier-matrices-alicia-jeannin","status":"publish","type":"event","link":"https:\/\/www.lasemaineduson.be\/en\/event\/atelier-matrices-alicia-jeannin\/","title":{"rendered":"Atelier Matrices &#8211; Alicia Jeannin"},"content":{"rendered":"<p><em><strong>Workshop 1 : mercredi 1 f\u00e9vrier, 14:00 &#8211; 16:00<\/strong><\/em><\/p>\n<p><em><strong>Workshop 2 : samedi 4 f\u00e9vrier, 15:00 &#8211; 17:00<\/strong><\/em><\/p>\n<p><em><strong>Max. 10 personnes par atelier<\/strong><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Pendant cet atelier, les participants seront amen\u00e9s \u00e0 manipuler leur propre voix \u00e0 l&#8217;aide des diff\u00e9rents dispositifs sonores de l&#8217;installation.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cDans un premier temps nous parlerons des origines de la parole, de ses chemins internes. Nous essaierons de prendre conscience de ce qui se passe en nous, mentalement et physiquement, lorsque nous disons quelque chose.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ensuite, je proposerai \u00e0 chacun d&#8217;enregistrer quelques mots et de les faire circuler dans plusieurs corps, mati\u00e8res et appareils, pour en observer les petites transformations. Suivant le principe d\u2019une sorte de \u00ab t\u00e9l\u00e9phone arabe \u00bb, nous verrons ce que deviennent ces paroles apr\u00e8s leur passage au sein de ces matrices et leur retransmission.\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les participant pourront s\u2019ils le souhaitent l\u00e9guer leurs enregistrements afin de contribuer \u00e0 l\u2019\u00e9volution de la pi\u00e8ce. Autant que possible les traces de ces exp\u00e9riences seront conserv\u00e9es et ajout\u00e9es \u00e0 l\u2019installation.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><br style=\"font-weight: 400;\" \/><br style=\"font-weight: 400;\" \/><\/p>\n","protected":false},"author":1,"featured_media":2040,"template":"","meta":{"_acf_changed":false,"footnotes":""},"lieu":[1059],"region":[],"event_type":[],"edition":[5],"class_list":["post-3707","event","type-event","status-publish","has-post-thumbnail","hentry","lieu-halles-saint-gery-caves","edition-5"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3707\/revisions"}],"predecessor-version":[{"id":5295,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event\/3707\/revisions\/5295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/media\/2040"}],"wp:attachment":[{"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/media?parent=3707"}],"wp:term":[{"taxonomy":"date","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/date?post=3707"},{"taxonomy":"lieu","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/lieu?post=3707"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/region?post=3707"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/event_type?post=3707"},{"taxonomy":"edition","embeddable":true,"href":"https:\/\/www.lasemaineduson.be\/en\/wp-json\/wp\/v2\/edition?post=3707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}